{"id":45558,"date":"2013-07-11T11:01:55","date_gmt":"2013-07-11T14:01:55","guid":{"rendered":"http:\/\/www.blogdopilako.com.br\/wp\/?p=45558"},"modified":"2013-07-11T11:01:55","modified_gmt":"2013-07-11T14:01:55","slug":"curiosidades-musicais-noel-rosa","status":"publish","type":"post","link":"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/","title":{"rendered":"Curiosidades Musicais: Noel Rosa"},"content":{"rendered":"\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-text=\"Curiosidades Musicais: Noel Rosa\" data-desc=\"Noel de Medeiros Rosa (Noel Rosa), nasceu no Rio de Janeiro, no dia 11 de dezembro de 1910 e faleceu no Rio no dia 04 de maio de 1937. Um dos maiores nomes da m\u00fasica popular brasileira, criado no bairro carioca de Vila Izabel, filho de Manuel Garcia de Medeiros Rosa e da professora Marta de\" data-image=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/11-10-24_a-preguic3a7a-na-cadc3aancia-do-samba_maria-rita-kehl.jpg\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div><p style=\"text-align: justify;\"><a href=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/11-10-24_a-preguic3a7a-na-cadc3aancia-do-samba_maria-rita-kehl.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-45560\" alt=\"11-10-24_a-preguic3a7a-na-cadc3aancia-do-samba_maria-rita-kehl\" src=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/11-10-24_a-preguic3a7a-na-cadc3aancia-do-samba_maria-rita-kehl.jpg\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Noel de Medeiros Rosa (Noel Rosa), nasceu no Rio de Janeiro, no dia 11 de dezembro de 1910 e faleceu no Rio no dia 04 de maio de 1937.<\/p>\n<p style=\"text-align: justify;\">Um dos maiores nomes da m\u00fasica popular brasileira, criado no bairro carioca de Vila Izabel, filho de Manuel Garcia de Medeiros Rosa e da professora Marta de Medeiros Rosa.<\/p>\n<p style=\"text-align: justify;\">Noel Rosa nasceu de um parto muito dif\u00edcil, que incluiu o uso de F\u00f3rceps pelo m\u00e9dico obstetra como medida para salvar as vidas da m\u00e3e e do beb\u00ea, o qual lhe causou fratura e afundou o maxilar inferior provocando tamb\u00e9m paralisia parcial no lado direito do seu rosto. Enfim, era at\u00e9 um defeito pequeno para um parto t\u00e3o dif\u00edcil e talvez, com o tempo, ele se recuperasse naturalmente.<\/p>\n<p style=\"text-align: justify;\">Mas o defeito do rosto acentuava-se \u00e0 medida que o menino crescia. Aos seis anos, quando j\u00e1 aprendia as primeiras letras com a m\u00e3e, foi operado, o mesmo aconteceu seis anos depois, mas a ortopedia da \u00e9poca n\u00e3o conseguiu nada.<\/p>\n<p style=\"text-align: justify;\">E foi no Col\u00e9gio S\u00e3o Bento, onde se matriculou em 28 de dezembro de 1923, que o menino de treze anos, ganhou o impiedoso apelido de \u201cqueixinho\u201d.<\/p>\n<p style=\"text-align: justify;\">O melhor que se pode dizer de Noel Rosa \u00e9 lembrar que, enquanto que para a maioria dos artistas populares a fama acaba um dia ap\u00f3s a morte, a dele s\u00f3 come\u00e7ou dez anos depois.<\/p>\n<p style=\"text-align: justify;\">Em 1931, Noel entrou para Faculdade de Medicina no firme prop\u00f3sito de ser m\u00e9dico, por\u00e9m o talento musical falou bem mais alto.<\/p>\n<p style=\"text-align: justify;\">Noel teve ao mesmo tempo v\u00e1rias namoradas e foi amante de muitas mulheres casadas.<\/p>\n<p style=\"text-align: justify;\">Casou-se em 1934 com uma mo\u00e7a da alta sociedade, Lindaura, mas era apaixonado mesmo por Ceci (Juraci Correia de Araujo) a prostituta do Cabar\u00e9, sua amante de longa data.<\/p>\n<p style=\"text-align: justify;\">O rapaz magrinho e acanhado falou para o violoncelista Homero Dornelas:<\/p>\n<p style=\"text-align: justify;\">&#8211; Homero, voc\u00ea sabe, eu n\u00e3o conhe\u00e7o m\u00fasica e queria que voc\u00ea escrevesse um samba que eu fiz hoje.<\/p>\n<p style=\"text-align: justify;\">O m\u00fasico sentou ao piano e pediu que o rapaz cantasse o samba.<\/p>\n<p style=\"text-align: justify;\">&#8211; Agora vou minha conduta<\/p>\n<p style=\"text-align: justify;\">&#8211; Eu vou pra luta, pois eu quero me aprumar<\/p>\n<p style=\"text-align: justify;\">&#8211; Vou tratar voc\u00ea com for\u00e7a bruta&#8230;<\/p>\n<p style=\"text-align: justify;\">Homero interrompeu:<\/p>\n<p style=\"text-align: justify;\">&#8211; Repete a primeira frase<\/p>\n<p style=\"text-align: justify;\">&#8211; Agora vou mudar minha conduta&#8230;<\/p>\n<p style=\"text-align: justify;\">&#8211; Espera a\u00ed Noel, este samba n\u00e3o pode ser publicado!<\/p>\n<p style=\"text-align: justify;\">&#8211; Ora essa, por qu\u00ea?<\/p>\n<p style=\"text-align: justify;\">&#8211; Porque isso n\u00e3o \u00e9 samba, \u00e9 o Hino Nacional!<\/p>\n<p style=\"text-align: justify;\">E tocou no piano os primeiros compassos do Hino, surpreendendo o sambista: &#8211; ouviram do Ipiranga as margens pl\u00e1cidas&#8230;<\/p>\n<p style=\"text-align: justify;\">&#8211; U\u00e9, mas \u00e9 a mesma melodia, e agora?<\/p>\n<p style=\"text-align: justify;\">&#8211; \u00c9 simples, basta uma ligeira modifica\u00e7\u00e3o no encadeamento mel\u00f3dico e o samba j\u00e1 fica outro.<\/p>\n<p style=\"text-align: justify;\">(Di\u00e1logo reproduzido por Almirante)<\/p>\n<p style=\"text-align: justify;\">E ali mesmo Dornelas trocou algumas notas, dando a forma definitiva ao samba (Com que Roupa), era o final de 1929.<\/p>\n<p style=\"text-align: justify;\">Contam que essa m\u00fasica ele se inspirou quando ia sair com os amigos de farra, e a m\u00e3e dele escondeu suas roupas e os amigos: vamos Noel e ele com pressa perguntou \u201ccom que roupa eu vou?\u201d.<\/p>\n<p style=\"text-align: justify;\">Autor de v\u00e1rias m\u00fasicas como: Palpite Infeliz, Pra que Mentir, Feiti\u00e7o da Vila, Feiti\u00e7o de Ora\u00e7\u00e3o, Gago Apaixonado, Tr\u00eas Apitos, Conversa de Botequim, Com que Roupa e tantas outras.<\/p>\n<p style=\"text-align: justify;\">Entre os int\u00e9rpretes que passaram a cantar seus sambas na \u00e9poca, destacam-se: M\u00e1rio Reis, Francisco Alves e Aracy de Almeida.<\/p>\n<p><strong>Com que Roupa?<br \/>\n<\/strong>Noel Rosa<\/p>\n<p><object width=\"600\" height=\"450\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"\/\/www.youtube.com\/v\/LxKJN-JodPI?hl=pt_BR&amp;version=3\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed width=\"600\" height=\"450\" type=\"application\/x-shockwave-flash\" src=\"\/\/www.youtube.com\/v\/LxKJN-JodPI?hl=pt_BR&amp;version=3\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<p>Agora vou mudar minha conduta<br \/>\nEu vou pra luta pois eu quero me aprumar<br \/>\nVou tratar voc\u00ea com a for\u00e7a bruta<br \/>\nPra poder me reabilitar<\/p>\n<p>Pois esta vida n\u00e3o est\u00e1 sopa<br \/>\nE eu pergunto: com que roupa?<br \/>\nCom que roupa que eu vou<br \/>\nPro samba que voc\u00ea me convidou?<br \/>\nCom que roupa que eu vou<br \/>\nPro samba que voc\u00ea me convidou?<\/p>\n<p>Agora eu n\u00e3o ando mais fagueiro<br \/>\nPois o dinheiro n\u00e3o \u00e9 f\u00e1cil de ganhar<br \/>\nMesmo eu sendo um cabra trapaceiro<br \/>\nN\u00e3o consigo ter nem pra gastar<\/p>\n<p>Eu j\u00e1 corri de vento em popa<br \/>\nMas agora com que roupa?<br \/>\nCom que roupa que eu vou<br \/>\nPro samba que voc\u00ea me convidou?<br \/>\nCom que roupa que eu vou<br \/>\nPro samba que voc\u00ea me convidou?<\/p>\n<p>Eu hoje estou pulando como sapo<br \/>\nPra ver se escapo desta praga de urubu<br \/>\nJ\u00e1 estou coberto de farrapo<br \/>\nEu vou acabar ficando nu<\/p>\n<p>Meu terno j\u00e1 virou estopa<br \/>\nE eu nem sei mais com que roupa<br \/>\nCom que roupa que eu vou<br \/>\nPro samba que voc\u00ea me convidou?<br \/>\nCom que roupa que eu vou<br \/>\nPro samba que voc\u00ea me convidou?<\/p>\n<p><strong><a href=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/leo.jpg\"><img loading=\"lazy\" class=\"alignleft\" alt=\"leo\" src=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/leo.jpg\" width=\"232\" height=\"194\" \/><\/a><\/strong><strong><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Leo dos Monges<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/radiosintoniabrasil.com.br\/\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-45563\" alt=\"Bot\u00e3o RSB\" src=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/Bot\u00e3o-RSB.jpg\" width=\"465\" height=\"80\" \/><\/a><\/p>\n\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-text=\"Curiosidades Musicais: Noel Rosa\" data-desc=\"Noel de Medeiros Rosa (Noel Rosa), nasceu no Rio de Janeiro, no dia 11 de dezembro de 1910 e faleceu no Rio no dia 04 de maio de 1937. Um dos maiores nomes da m\u00fasica popular brasileira, criado no bairro carioca de Vila Izabel, filho de Manuel Garcia de Medeiros Rosa e da professora Marta de\" data-image=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/11-10-24_a-preguic3a7a-na-cadc3aancia-do-samba_maria-rita-kehl.jpg\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div>","protected":false},"excerpt":{"rendered":"\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-text=\"Curiosidades Musicais: Noel Rosa\" data-desc=\"Noel de Medeiros Rosa (Noel Rosa), nasceu no Rio de Janeiro, no dia 11 de dezembro de 1910 e faleceu no Rio no dia 04 de maio de 1937. Um dos maiores nomes da m\u00fasica popular brasileira, criado no bairro carioca de Vila Izabel, filho de Manuel Garcia de Medeiros Rosa e da professora Marta de\" data-image=\"\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div><p>Noel de Medeiros Rosa (Noel Rosa), nasceu no Rio de Janeiro, no dia 11 de dezembro de 1910 e faleceu no Rio no dia 04 de maio de 1937. Um dos maiores nomes da m\u00fasica popular brasileira, criado no bairro &hellip; <a href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2013\/07\/11\/curiosidades-musicais-noel-rosa\/\" data-text=\"Curiosidades Musicais: Noel Rosa\" data-desc=\"Noel de Medeiros Rosa (Noel Rosa), nasceu no Rio de Janeiro, no dia 11 de dezembro de 1910 e faleceu no Rio no dia 04 de maio de 1937. Um dos maiores nomes da m\u00fasica popular brasileira, criado no bairro carioca de Vila Izabel, filho de Manuel Garcia de Medeiros Rosa e da professora Marta de\" data-image=\"\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[129],"tags":[],"_links":{"self":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts\/45558"}],"collection":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/comments?post=45558"}],"version-history":[{"count":2,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts\/45558\/revisions"}],"predecessor-version":[{"id":45565,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts\/45558\/revisions\/45565"}],"wp:attachment":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/media?parent=45558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/categories?post=45558"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/tags?post=45558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}