{"id":115870,"date":"2018-08-22T14:20:10","date_gmt":"2018-08-22T17:20:10","guid":{"rendered":"http:\/\/www.blogdopilako.com.br\/wp\/?p=115870"},"modified":"2018-08-22T22:13:45","modified_gmt":"2018-08-23T01:13:45","slug":"momento-cultural-tua-partida-por-dilson-lira-2","status":"publish","type":"post","link":"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/","title":{"rendered":"Momento Cultural: TUA PARTIDA \u2013 Por Dilson Lira."},"content":{"rendered":"\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-text=\"Momento Cultural: TUA PARTIDA \u2013 Por Dilson Lira.\" data-desc=\"\u00c0 Cl\u00e9a, adorada esposa. Ave que parte, gorjeiante e amiga, por estes c\u00e9us de l\u00edvidos luares, aonde hei de ouvir os teus cantares? Aonde tu\u2019alma l\u00edrica se abriga?\/Aonde ouvirei a r\u00fastica cantiga, que outrora ouvi aos s\u00f3rdidos pesares, aonde tu v\u00e1s, tu queres que eu te siga, por outras\" data-image=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/2018\/08\/Dilson-Lira-Jornal-da-Vitoria.jpg\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div><p align=\"right\"><a href=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/2018\/08\/Dilson-Lira-Jornal-da-Vitoria.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-115871\" src=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/2018\/08\/Dilson-Lira-Jornal-da-Vitoria.jpg\" alt=\"\" width=\"527\" height=\"644\" srcset=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/2018\/08\/Dilson-Lira-Jornal-da-Vitoria.jpg 527w, http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/2018\/08\/Dilson-Lira-Jornal-da-Vitoria-245x300.jpg 245w\" sizes=\"(max-width: 527px) 100vw, 527px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"right\">\u00c0 Cl\u00e9a, adorada esposa.<\/p>\n<p style=\"text-align: justify;\">Ave que parte, gorjeiante e amiga,<br \/>\npor estes c\u00e9us de l\u00edvidos luares,<br \/>\naonde hei de ouvir os teus cantares?<br \/>\nAonde tu\u2019alma l\u00edrica se abriga?\/Aonde ouvirei a r\u00fastica cantiga,<br \/>\nque outrora ouvi aos s\u00f3rdidos pesares,<br \/>\naonde tu v\u00e1s, tu queres que eu te siga,<br \/>\npor outras piagas, em estranhos ares?\/N\u00e3o parte, ave, aqui \u00e9 doce a vida!<br \/>\nA brisa \u00e9 fresca e \u00e9 mais quente o ninho,<br \/>\nA mataria \u00e9 verde e mais florida!\/Mas, se partires, aonde quer que fores,<br \/>\nsaibas que em mim atravessou-se um espinho,<br \/>\nporque contigo foram os meus amores!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Manoel Dilson Lira da Silva<\/strong>, vitoriense nascido aos 30 de novembro de 1925. Filho de Jo\u00e3o Manoel da Silva e Maria Lira da Silva. Fez seus estudos no \u201cGin\u00e1sio da Vit\u00f3ria\u201d. Poeta nato, tem publicados tr\u00eas livros de poemas. Intelig\u00eancia l\u00facida, muito ainda temos de esperar de suas produ\u00e7\u00f5es po\u00e9ticas.<\/p>\n\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-text=\"Momento Cultural: TUA PARTIDA \u2013 Por Dilson Lira.\" data-desc=\"\u00c0 Cl\u00e9a, adorada esposa. Ave que parte, gorjeiante e amiga, por estes c\u00e9us de l\u00edvidos luares, aonde hei de ouvir os teus cantares? Aonde tu\u2019alma l\u00edrica se abriga?\/Aonde ouvirei a r\u00fastica cantiga, que outrora ouvi aos s\u00f3rdidos pesares, aonde tu v\u00e1s, tu queres que eu te siga, por outras\" data-image=\"http:\/\/www.blogdopilako.com.br\/wp\/wp-content\/uploads\/2018\/08\/Dilson-Lira-Jornal-da-Vitoria.jpg\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div>","protected":false},"excerpt":{"rendered":"\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-text=\"Momento Cultural: TUA PARTIDA \u2013 Por Dilson Lira.\" data-desc=\"\u00c0 Cl\u00e9a, adorada esposa. Ave que parte, gorjeiante e amiga, por estes c\u00e9us de l\u00edvidos luares, aonde hei de ouvir os teus cantares? Aonde tu\u2019alma l\u00edrica se abriga?\/Aonde ouvirei a r\u00fastica cantiga, que outrora ouvi aos s\u00f3rdidos pesares, aonde tu v\u00e1s, tu queres que eu te siga, por outras\" data-image=\"\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div><p>\u00c0 Cl\u00e9a, adorada esposa. Ave que parte, gorjeiante e amiga, por estes c\u00e9us de l\u00edvidos luares, aonde hei de ouvir os teus cantares? Aonde tu\u2019alma l\u00edrica se abriga?\/Aonde ouvirei a r\u00fastica cantiga, que outrora ouvi aos s\u00f3rdidos pesares, aonde tu &hellip; <a href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n\n\t\t\t\t<div class=\"mr_social_sharing_wrapper\">\n\t\t\t\t<!-- Social Sharing Toolkit v2.2 --><span class=\"mr_social_sharing_top\"><span style=\"display: inline-block; width: 55px; height: 62px; overflow: hidden;\"><div class=\"fb-like\" data-href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-send=\"false\" data-layout=\"box_count\" data-width=\"55\" data-show-faces=\"false\"><\/div><\/span><\/span><span class=\"mr_social_sharing_top\"><fb:share-button type=\"box_count\" href=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\"><\/fb:share-button><\/span><span class=\"mr_social_sharing\"><a rel=\"nofollow\" class=\"linksalpha_button linksalpha_link\" href=\"\/\/www.linksalpha.com\/social\/mobile\" data-url=\"http:\/\/www.blogdopilako.com.br\/wp\/2018\/08\/22\/momento-cultural-tua-partida-por-dilson-lira-2\/\" data-text=\"Momento Cultural: TUA PARTIDA \u2013 Por Dilson Lira.\" data-desc=\"\u00c0 Cl\u00e9a, adorada esposa. Ave que parte, gorjeiante e amiga, por estes c\u00e9us de l\u00edvidos luares, aonde hei de ouvir os teus cantares? Aonde tu\u2019alma l\u00edrica se abriga?\/Aonde ouvirei a r\u00fastica cantiga, que outrora ouvi aos s\u00f3rdidos pesares, aonde tu v\u00e1s, tu queres que eu te siga, por outras\" data-image=\"\" data-button=\"none\">\n\t\t\t\t\t<img src=\"\/\/www.linksalpha.com\/images\/social_share_button.png\" alt=\"Share\" class=\"linksalpha_image\" \/>\n\t\t\t\t\t<\/a><script type=\"text\/javascript\" src=\"\/\/www.linksalpha.com\/scripts\/loader_iconbox.js?v=2.4\"><\/script><\/span><\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[114],"tags":[],"_links":{"self":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts\/115870"}],"collection":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/comments?post=115870"}],"version-history":[{"count":4,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts\/115870\/revisions"}],"predecessor-version":[{"id":115887,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/posts\/115870\/revisions\/115887"}],"wp:attachment":[{"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/media?parent=115870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/categories?post=115870"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.blogdopilako.com.br\/wp\/wp-json\/wp\/v2\/tags?post=115870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}